{"id":15262,"date":"2020-12-03T15:01:50","date_gmt":"2020-12-03T14:01:50","guid":{"rendered":"https:\/\/hardware.mipu.eu\/?post_type=product&#038;p=15262"},"modified":"2020-12-03T15:04:56","modified_gmt":"2020-12-03T14:04:56","slug":"corso-online-machine-learning-per-la-manutenzione-predittiva-focus-pratico","status":"publish","type":"product","link":"https:\/\/hw.mipu.eu\/es\/prodotto\/corso-online-machine-learning-per-la-manutenzione-predittiva-focus-pratico\/","title":{"rendered":"CORSO ONLINE &#8211; Machine Learning per la Manutenzione Predittiva: focus pratico"},"content":{"rendered":"<p>21-22 Ottobre 2021 dalle 9.00 alle 13.00<\/p>\n<p style=\"text-align: justify;\">Il corso ha l&#8217;obiettivo di fornire terminologia, concetti di base e competenze utili per comprendere come applicare il Machine Learning nel contesto della Manutenzione.<\/p>\n<p><strong>CONTENUTI<br \/>\n<\/strong>&#8211; Introduzione all&#8217;Intelligenza Artificiale e al Machine Learning<br \/>\n&#8211; Algoritmi e tecniche di Machine Learning: il flusso di lavoro del Machine Learning<br \/>\n&#8211; I dati: quanti, quali e come presentarli<br \/>\n&#8211; Machine Learning per la Manutenzione<br \/>\n&#8211; Esercitazioni pratiche: sviluppo di modelli di Machine Learning su un asset a scelta per il controllo delle performance<br \/>\n&#8211; Analisi e manipolazione dei dati forniti<br \/>\n&#8211; Organizzazione database in base ai dati forniti<br \/>\n&#8211; Implementazione modello per il controllo delle performance dell&#8217;asset in esame<br \/>\n&#8211; Identificazione della migliore strategia algoritmica per lo scopo definito<br \/>\n&#8211; Implementazione degli algoritmi che costituiscono l&#8217;Intelligenza<br \/>\n&#8211; Validazione variabili di interesse<br \/>\n&#8211; Analisi dei dati, correlazioni e visualizzazione<\/p>\n<p><strong>DESTINATARI<br \/>\n<\/strong><\/p>\n<p>Rivolto a: Ingegneri di Processo, Meccanici, Elettrici.<\/p>\n<p><strong>DURATA<\/strong><br \/>\nCorso online dalle ore 9:00 alle ore 13:00 entrambi i giorni (8 ore)<\/p>\n<p>Il corso \u00e8 <strong>online<\/strong>: avrai la possibilit\u00e0 di porre domande e confrontarti con il docente e gli altri partecipanti.<\/p>\n<p style=\"text-align: center;\"><strong>A seguito dell\u2019acquisto, riceverai una e-mail di conferma<\/strong><br \/>\n<strong>con il link di accesso al corso nei giorni stabiliti.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il corso ha l&#8217;obiettivo di fornire terminologia, concetti di base e competenze utili per comprendere come applicare il Machine Learning nel contesto della Manutenzione.<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":""},"product_cat":[215,173],"product_tag":[],"class_list":{"0":"post-15262","1":"product","2":"type-product","3":"status-publish","5":"product_cat-ai-2","6":"product_cat-manutenzione-predittiva","7":"entry","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>CORSO ONLINE - Machine Learning per la Manutenzione Predittiva: focus pratico - Mipu Hardware<\/title>\n<meta name=\"description\" content=\"Il corso ha l&#039;obiettivo di fornire terminologia, concetti di base e competenze utili per comprendere come applicare il Machine Learning nel contesto della Manutenzione.\" \/>\n<meta name=\"robots\" content=\"index, nofollow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hw.mipu.eu\/es\/prodotto\/corso-online-machine-learning-per-la-manutenzione-predittiva-focus-pratico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CORSO ONLINE - Machine Learning per la Manutenzione Predittiva: focus pratico - Mipu Hardware\" \/>\n<meta property=\"og:description\" content=\"Il corso ha l&#039;obiettivo di fornire terminologia, concetti di base e competenze utili per comprendere come applicare il Machine Learning nel contesto della Manutenzione.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hw.mipu.eu\/es\/prodotto\/corso-online-machine-learning-per-la-manutenzione-predittiva-focus-pratico\/\" \/>\n<meta property=\"og:site_name\" content=\"Mipu Hardware\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-03T14:04:56+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hw.mipu.eu\/es\/prodotto\/corso-online-machine-learning-per-la-manutenzione-predittiva-focus-pratico\/\",\"url\":\"https:\/\/hw.mipu.eu\/es\/prodotto\/corso-online-machine-learning-per-la-manutenzione-predittiva-focus-pratico\/\",\"name\":\"CORSO ONLINE - Machine Learning per la Manutenzione Predittiva: focus pratico - Mipu Hardware\",\"isPartOf\":{\"@id\":\"https:\/\/hw.mipu.eu\/es\/#website\"},\"datePublished\":\"2020-12-03T14:01:50+00:00\",\"dateModified\":\"2020-12-03T14:04:56+00:00\",\"description\":\"Il corso ha l'obiettivo di fornire terminologia, concetti di base e competenze utili per comprendere come applicare il Machine Learning nel contesto della Manutenzione.\",\"breadcrumb\":{\"@id\":\"https:\/\/hw.mipu.eu\/es\/prodotto\/corso-online-machine-learning-per-la-manutenzione-predittiva-focus-pratico\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hw.mipu.eu\/es\/prodotto\/corso-online-machine-learning-per-la-manutenzione-predittiva-focus-pratico\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hw.mipu.eu\/es\/prodotto\/corso-online-machine-learning-per-la-manutenzione-predittiva-focus-pratico\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/hw.mipu.eu\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CORSO ONLINE &#8211; Machine Learning per la Manutenzione Predittiva: focus pratico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hw.mipu.eu\/es\/#website\",\"url\":\"https:\/\/hw.mipu.eu\/es\/\",\"name\":\"Mipu Hardware\",\"description\":\"Predictive Hub\",\"publisher\":{\"@id\":\"https:\/\/hw.mipu.eu\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hw.mipu.eu\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/hw.mipu.eu\/es\/#organization\",\"name\":\"Mipu Hardware\",\"url\":\"https:\/\/hw.mipu.eu\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/hw.mipu.eu\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/hw.mipu.eu\/wp-content\/uploads\/sites\/5\/2020\/04\/cropped-Logotipo-MIPU.png\",\"contentUrl\":\"https:\/\/hw.mipu.eu\/wp-content\/uploads\/sites\/5\/2020\/04\/cropped-Logotipo-MIPU.png\",\"width\":1523,\"height\":588,\"caption\":\"Mipu Hardware\"},\"image\":{\"@id\":\"https:\/\/hw.mipu.eu\/es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CORSO ONLINE - Machine Learning per la Manutenzione Predittiva: focus pratico - Mipu Hardware","description":"Il corso ha l'obiettivo di fornire terminologia, concetti di base e competenze utili per comprendere come applicare il Machine Learning nel contesto della Manutenzione.","robots":{"index":"index","follow":"nofollow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hw.mipu.eu\/es\/prodotto\/corso-online-machine-learning-per-la-manutenzione-predittiva-focus-pratico\/","og_locale":"es_ES","og_type":"article","og_title":"CORSO ONLINE - Machine Learning per la Manutenzione Predittiva: focus pratico - Mipu Hardware","og_description":"Il corso ha l'obiettivo di fornire terminologia, concetti di base e competenze utili per comprendere come applicare il Machine Learning nel contesto della Manutenzione.","og_url":"https:\/\/hw.mipu.eu\/es\/prodotto\/corso-online-machine-learning-per-la-manutenzione-predittiva-focus-pratico\/","og_site_name":"Mipu Hardware","article_modified_time":"2020-12-03T14:04:56+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hw.mipu.eu\/es\/prodotto\/corso-online-machine-learning-per-la-manutenzione-predittiva-focus-pratico\/","url":"https:\/\/hw.mipu.eu\/es\/prodotto\/corso-online-machine-learning-per-la-manutenzione-predittiva-focus-pratico\/","name":"CORSO ONLINE - Machine Learning per la Manutenzione Predittiva: focus pratico - Mipu Hardware","isPartOf":{"@id":"https:\/\/hw.mipu.eu\/es\/#website"},"datePublished":"2020-12-03T14:01:50+00:00","dateModified":"2020-12-03T14:04:56+00:00","description":"Il corso ha l'obiettivo di fornire terminologia, concetti di base e competenze utili per comprendere come applicare il Machine Learning nel contesto della Manutenzione.","breadcrumb":{"@id":"https:\/\/hw.mipu.eu\/es\/prodotto\/corso-online-machine-learning-per-la-manutenzione-predittiva-focus-pratico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hw.mipu.eu\/es\/prodotto\/corso-online-machine-learning-per-la-manutenzione-predittiva-focus-pratico\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hw.mipu.eu\/es\/prodotto\/corso-online-machine-learning-per-la-manutenzione-predittiva-focus-pratico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hw.mipu.eu\/es\/"},{"@type":"ListItem","position":2,"name":"CORSO ONLINE &#8211; Machine Learning per la Manutenzione Predittiva: focus pratico"}]},{"@type":"WebSite","@id":"https:\/\/hw.mipu.eu\/es\/#website","url":"https:\/\/hw.mipu.eu\/es\/","name":"Mipu Hardware","description":"Predictive Hub","publisher":{"@id":"https:\/\/hw.mipu.eu\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hw.mipu.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/hw.mipu.eu\/es\/#organization","name":"Mipu Hardware","url":"https:\/\/hw.mipu.eu\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hw.mipu.eu\/es\/#\/schema\/logo\/image\/","url":"https:\/\/hw.mipu.eu\/wp-content\/uploads\/sites\/5\/2020\/04\/cropped-Logotipo-MIPU.png","contentUrl":"https:\/\/hw.mipu.eu\/wp-content\/uploads\/sites\/5\/2020\/04\/cropped-Logotipo-MIPU.png","width":1523,"height":588,"caption":"Mipu Hardware"},"image":{"@id":"https:\/\/hw.mipu.eu\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hw.mipu.eu\/es\/wp-json\/wp\/v2\/product\/15262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hw.mipu.eu\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/hw.mipu.eu\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/hw.mipu.eu\/es\/wp-json\/wp\/v2\/comments?post=15262"}],"wp:attachment":[{"href":"https:\/\/hw.mipu.eu\/es\/wp-json\/wp\/v2\/media?parent=15262"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/hw.mipu.eu\/es\/wp-json\/wp\/v2\/product_cat?post=15262"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/hw.mipu.eu\/es\/wp-json\/wp\/v2\/product_tag?post=15262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}