{"id":10724,"date":"2020-09-09T10:50:03","date_gmt":"2020-09-09T08:50:03","guid":{"rendered":"https:\/\/hardware.mipu.eu\/?post_type=product&#038;p=10724"},"modified":"2021-02-09T11:29:22","modified_gmt":"2021-02-09T10:29:22","slug":"analisi-delle-vibrazioni","status":"publish","type":"product","link":"https:\/\/hw.mipu.eu\/fr\/prodotto\/analisi-delle-vibrazioni\/","title":{"rendered":"Corso analisi delle vibrazioni cat. 1+2 + certificazione ISO 18436-2"},"content":{"rendered":"<p>Il corso ha come obiettivo quello di essere in grado di introdurre un programma di controlli predittivi ed essere in grado di configurare correttamente le misure vibrazionali in impianto.<\/p>\n<p><strong>CONTENUTI<\/strong><br \/>\n&#8211; Panoramica sui diversi concetti di manutenzione<br \/>\n&#8211; Presentazione della manutenzione predittiva e delle sue tecniche<br \/>\n&#8211; Fondamenti di teoria alla base dell&rsquo;analisi delle vibrazioni<br \/>\n&#8211; Come analizzare spettri, onde temporali, modulazioni e misurazioni di fase<br \/>\n&#8211; Diagnostica guasti: sbilanciamento, disallineamento, gioco, difetti di cuscinetto, risonanza, cavitazione<br \/>\n&#8211; Detenzione di problemi elettrici con l&rsquo;analisi spettrale delle correnti e del campo magnetico<br \/>\n&#8211; Come raccogliere buone misure e ripetibili nel tempo<br \/>\n&#8211; Come impostare soglie di allarme<br \/>\n&#8211; Sessione pratica con utilizzo della strumentazione<\/p>\n<p><strong>DESTINATARI<br \/>\n<\/strong>Responsabili di Manutenzione, Tecnici di Manutenzione, Reliability Engineer.<\/p>\n<p><strong>DURATA<br \/>\n<\/strong>4 giorni dalle ore 9:00 alle ore 18:00<\/p>\n<p>Il corso sar\u00e0 online: avrai la possibilit\u00e0 di porre domande e confrontarti con il docente e gli altri partecipanti. Alla fine del corso verr\u00e0 tenuto l&rsquo;esame per l&rsquo;ottenimento della certificazione ISO 18436-2.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il corso fornisce le competenze per <strong>diagnosticare difetti<\/strong> accuratamente, impostare limiti di allarme, comprendere le analisi temporali e di fase oltre che i parametri degli analizzatori e <strong>configurare correttamente una misura vibrazionale<\/strong>.<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":""},"product_cat":[173],"product_tag":[],"class_list":{"0":"post-10724","1":"product","2":"type-product","3":"status-publish","5":"product_cat-manutenzione-predittiva","6":"entry","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Corso analisi delle vibrazioni cat. 1+2 + certificazione ISO 18436-2 - Mipu Hardware<\/title>\n<meta name=\"robots\" content=\"index, nofollow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hw.mipu.eu\/fr\/prodotto\/analisi-delle-vibrazioni\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Corso analisi delle vibrazioni cat. 1+2 + certificazione ISO 18436-2 - Mipu Hardware\" \/>\n<meta property=\"og:description\" content=\"Il corso fornisce le competenze per diagnosticare difetti accuratamente, impostare limiti di allarme, comprendere le analisi temporali e di fase oltre che i parametri degli analizzatori e configurare correttamente una misura vibrazionale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hw.mipu.eu\/fr\/prodotto\/analisi-delle-vibrazioni\/\" \/>\n<meta property=\"og:site_name\" content=\"Mipu Hardware\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-09T10:29:22+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hw.mipu.eu\/fr\/prodotto\/analisi-delle-vibrazioni\/\",\"url\":\"https:\/\/hw.mipu.eu\/fr\/prodotto\/analisi-delle-vibrazioni\/\",\"name\":\"Corso analisi delle vibrazioni cat. 1+2 + certificazione ISO 18436-2 - Mipu Hardware\",\"isPartOf\":{\"@id\":\"https:\/\/hw.mipu.eu\/fr\/#website\"},\"datePublished\":\"2020-09-09T08:50:03+00:00\",\"dateModified\":\"2021-02-09T10:29:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/hw.mipu.eu\/fr\/prodotto\/analisi-delle-vibrazioni\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hw.mipu.eu\/fr\/prodotto\/analisi-delle-vibrazioni\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hw.mipu.eu\/fr\/prodotto\/analisi-delle-vibrazioni\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/hw.mipu.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Corso analisi delle vibrazioni cat. 1+2 + certificazione ISO 18436-2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hw.mipu.eu\/fr\/#website\",\"url\":\"https:\/\/hw.mipu.eu\/fr\/\",\"name\":\"Mipu Hardware\",\"description\":\"Predictive Hub\",\"publisher\":{\"@id\":\"https:\/\/hw.mipu.eu\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hw.mipu.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/hw.mipu.eu\/fr\/#organization\",\"name\":\"Mipu Hardware\",\"url\":\"https:\/\/hw.mipu.eu\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/hw.mipu.eu\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/hw.mipu.eu\/wp-content\/uploads\/sites\/5\/2020\/04\/cropped-Logotipo-MIPU.png\",\"contentUrl\":\"https:\/\/hw.mipu.eu\/wp-content\/uploads\/sites\/5\/2020\/04\/cropped-Logotipo-MIPU.png\",\"width\":1523,\"height\":588,\"caption\":\"Mipu Hardware\"},\"image\":{\"@id\":\"https:\/\/hw.mipu.eu\/fr\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Corso analisi delle vibrazioni cat. 1+2 + certificazione ISO 18436-2 - Mipu Hardware","robots":{"index":"index","follow":"nofollow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hw.mipu.eu\/fr\/prodotto\/analisi-delle-vibrazioni\/","og_locale":"fr_FR","og_type":"article","og_title":"Corso analisi delle vibrazioni cat. 1+2 + certificazione ISO 18436-2 - Mipu Hardware","og_description":"Il corso fornisce le competenze per diagnosticare difetti accuratamente, impostare limiti di allarme, comprendere le analisi temporali e di fase oltre che i parametri degli analizzatori e configurare correttamente una misura vibrazionale.","og_url":"https:\/\/hw.mipu.eu\/fr\/prodotto\/analisi-delle-vibrazioni\/","og_site_name":"Mipu Hardware","article_modified_time":"2021-02-09T10:29:22+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hw.mipu.eu\/fr\/prodotto\/analisi-delle-vibrazioni\/","url":"https:\/\/hw.mipu.eu\/fr\/prodotto\/analisi-delle-vibrazioni\/","name":"Corso analisi delle vibrazioni cat. 1+2 + certificazione ISO 18436-2 - Mipu Hardware","isPartOf":{"@id":"https:\/\/hw.mipu.eu\/fr\/#website"},"datePublished":"2020-09-09T08:50:03+00:00","dateModified":"2021-02-09T10:29:22+00:00","breadcrumb":{"@id":"https:\/\/hw.mipu.eu\/fr\/prodotto\/analisi-delle-vibrazioni\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hw.mipu.eu\/fr\/prodotto\/analisi-delle-vibrazioni\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hw.mipu.eu\/fr\/prodotto\/analisi-delle-vibrazioni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hw.mipu.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Corso analisi delle vibrazioni cat. 1+2 + certificazione ISO 18436-2"}]},{"@type":"WebSite","@id":"https:\/\/hw.mipu.eu\/fr\/#website","url":"https:\/\/hw.mipu.eu\/fr\/","name":"Mipu Hardware","description":"Predictive Hub","publisher":{"@id":"https:\/\/hw.mipu.eu\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hw.mipu.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/hw.mipu.eu\/fr\/#organization","name":"Mipu Hardware","url":"https:\/\/hw.mipu.eu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/hw.mipu.eu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/hw.mipu.eu\/wp-content\/uploads\/sites\/5\/2020\/04\/cropped-Logotipo-MIPU.png","contentUrl":"https:\/\/hw.mipu.eu\/wp-content\/uploads\/sites\/5\/2020\/04\/cropped-Logotipo-MIPU.png","width":1523,"height":588,"caption":"Mipu Hardware"},"image":{"@id":"https:\/\/hw.mipu.eu\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hw.mipu.eu\/fr\/wp-json\/wp\/v2\/product\/10724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hw.mipu.eu\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/hw.mipu.eu\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/hw.mipu.eu\/fr\/wp-json\/wp\/v2\/comments?post=10724"}],"wp:attachment":[{"href":"https:\/\/hw.mipu.eu\/fr\/wp-json\/wp\/v2\/media?parent=10724"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/hw.mipu.eu\/fr\/wp-json\/wp\/v2\/product_cat?post=10724"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/hw.mipu.eu\/fr\/wp-json\/wp\/v2\/product_tag?post=10724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}