{"id":14641,"date":"2020-11-18T08:39:08","date_gmt":"2020-11-18T07:39:08","guid":{"rendered":"https:\/\/hardware.mipu.eu\/?post_type=product&#038;p=14641"},"modified":"2020-11-18T08:49:06","modified_gmt":"2020-11-18T07:49:06","slug":"corso-online-comprehensive-energy-management","status":"publish","type":"product","link":"https:\/\/hw.mipu.eu\/fr\/prodotto\/corso-online-comprehensive-energy-management\/","title":{"rendered":"CORSO ONLINE &#8211; COMPREHENSIVE ENERGY MANAGEMENT"},"content":{"rendered":"<p>28 Gennaio dalle 9.00 alle 13.00<\/p>\n<p style=\"text-align: justify;\">L&rsquo;obiettivo del corso \u00e8 conoscere e valutare agevolazioni e titoli di efficienza energetica\u00a0per l\u2019attuazione di opere di efficientamento.<\/p>\n<p><strong>CONTENUTI<br \/>\n<\/strong><\/p>\n<ul>\n<li>Dalla diagnosi energetica allo studio di fattibilit\u00e0 delle opportunit\u00e0 di miglioramento;<\/li>\n<li>L\u2019importanza dell\u2019analisi economica nella proposta di piani di miglioramento;<\/li>\n<li>Analisi costi benefici: principi e metodologie di calcolo;<\/li>\n<li>Indici economici e finanziari per la valutazione degli interventi: payback period, indice di profitto e tempo di ritorno attualizzato;<\/li>\n<li>Analisi costi benefici e analisi di sensibilit\u00e0;<\/li>\n<li>Certificati di efficienza energetica e incentivi per le azioni di efficientamento energetico;<\/li>\n<li>Analisi del ciclo di vita e analisi costi benefici: differenze ed elementi in comune;<\/li>\n<li>Casi di studio: l\u2019analisi costi benefici nei progetti di miglioramento dell\u2019efficienza energetica.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>DESTINATARI<\/strong><br \/>\nConsulenti, Energy Manager, ESCO<\/p>\n<p><strong>DURATA<\/strong><br \/>\n4 ore.<br \/>\nll corso \u00e8 <strong>online<\/strong>: avrai la possibilit\u00e0 di porre domande e confrontarti con il docente e gli altri partecipanti.<\/p>\n<p style=\"text-align: center;\"><strong>A seguito dell\u2019acquisto, riceverai una e-mail di conferma<br \/>\ncon il link di accesso al corso nei giorni stabiliti.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>28 Gennaio dalle 9.00 alle 13.00 L&rsquo;obiettivo del corso \u00e8 conoscere e valutare agevolazioni e titoli di efficienza energetica\u00a0per l\u2019attuazione di opere di efficientamento. CONTENUTI Dalla diagnosi energetica allo studio di fattibilit\u00e0 delle opportunit\u00e0 di miglioramento; L\u2019importanza dell\u2019analisi economica nella proposta di piani di miglioramento; Analisi costi benefici: principi e metodologie di calcolo; Indici economici [&hellip;]<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":""},"product_cat":[215,184],"product_tag":[],"class_list":{"0":"post-14641","1":"product","2":"type-product","3":"status-publish","5":"product_cat-ai-2","6":"product_cat-efficienza-energetica","7":"entry","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>CORSO ONLINE - COMPREHENSIVE ENERGY MANAGEMENT - Mipu Hardware<\/title>\n<meta name=\"description\" content=\"L&#039;obiettivo del corso \u00e8 conoscere e valutare agevolazioni e titoli di efficienza energetica\u00a0per l\u2019attuazione di opere di efficientamento.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hw.mipu.eu\/fr\/prodotto\/corso-online-comprehensive-energy-management\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CORSO ONLINE - COMPREHENSIVE ENERGY MANAGEMENT - Mipu Hardware\" \/>\n<meta property=\"og:description\" content=\"L&#039;obiettivo del corso \u00e8 conoscere e valutare agevolazioni e titoli di efficienza energetica\u00a0per l\u2019attuazione di opere di efficientamento.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hw.mipu.eu\/fr\/prodotto\/corso-online-comprehensive-energy-management\/\" \/>\n<meta property=\"og:site_name\" content=\"Mipu Hardware\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-18T07:49:06+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hw.mipu.eu\/fr\/prodotto\/corso-online-comprehensive-energy-management\/\",\"url\":\"https:\/\/hw.mipu.eu\/fr\/prodotto\/corso-online-comprehensive-energy-management\/\",\"name\":\"CORSO ONLINE - COMPREHENSIVE ENERGY MANAGEMENT - Mipu Hardware\",\"isPartOf\":{\"@id\":\"https:\/\/hw.mipu.eu\/fr\/#website\"},\"datePublished\":\"2020-11-18T07:39:08+00:00\",\"dateModified\":\"2020-11-18T07:49:06+00:00\",\"description\":\"L'obiettivo del corso \u00e8 conoscere e valutare agevolazioni e titoli di efficienza energetica\u00a0per l\u2019attuazione di opere di efficientamento.\",\"breadcrumb\":{\"@id\":\"https:\/\/hw.mipu.eu\/fr\/prodotto\/corso-online-comprehensive-energy-management\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hw.mipu.eu\/fr\/prodotto\/corso-online-comprehensive-energy-management\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hw.mipu.eu\/fr\/prodotto\/corso-online-comprehensive-energy-management\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/hw.mipu.eu\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CORSO ONLINE &#8211; COMPREHENSIVE ENERGY MANAGEMENT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hw.mipu.eu\/fr\/#website\",\"url\":\"https:\/\/hw.mipu.eu\/fr\/\",\"name\":\"Mipu Hardware\",\"description\":\"Predictive Hub\",\"publisher\":{\"@id\":\"https:\/\/hw.mipu.eu\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hw.mipu.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/hw.mipu.eu\/fr\/#organization\",\"name\":\"Mipu Hardware\",\"url\":\"https:\/\/hw.mipu.eu\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/hw.mipu.eu\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/hw.mipu.eu\/wp-content\/uploads\/sites\/5\/2020\/04\/cropped-Logotipo-MIPU.png\",\"contentUrl\":\"https:\/\/hw.mipu.eu\/wp-content\/uploads\/sites\/5\/2020\/04\/cropped-Logotipo-MIPU.png\",\"width\":1523,\"height\":588,\"caption\":\"Mipu Hardware\"},\"image\":{\"@id\":\"https:\/\/hw.mipu.eu\/fr\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CORSO ONLINE - COMPREHENSIVE ENERGY MANAGEMENT - Mipu Hardware","description":"L'obiettivo del corso \u00e8 conoscere e valutare agevolazioni e titoli di efficienza energetica\u00a0per l\u2019attuazione di opere di efficientamento.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hw.mipu.eu\/fr\/prodotto\/corso-online-comprehensive-energy-management\/","og_locale":"fr_FR","og_type":"article","og_title":"CORSO ONLINE - COMPREHENSIVE ENERGY MANAGEMENT - Mipu Hardware","og_description":"L'obiettivo del corso \u00e8 conoscere e valutare agevolazioni e titoli di efficienza energetica\u00a0per l\u2019attuazione di opere di efficientamento.","og_url":"https:\/\/hw.mipu.eu\/fr\/prodotto\/corso-online-comprehensive-energy-management\/","og_site_name":"Mipu Hardware","article_modified_time":"2020-11-18T07:49:06+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hw.mipu.eu\/fr\/prodotto\/corso-online-comprehensive-energy-management\/","url":"https:\/\/hw.mipu.eu\/fr\/prodotto\/corso-online-comprehensive-energy-management\/","name":"CORSO ONLINE - COMPREHENSIVE ENERGY MANAGEMENT - Mipu Hardware","isPartOf":{"@id":"https:\/\/hw.mipu.eu\/fr\/#website"},"datePublished":"2020-11-18T07:39:08+00:00","dateModified":"2020-11-18T07:49:06+00:00","description":"L'obiettivo del corso \u00e8 conoscere e valutare agevolazioni e titoli di efficienza energetica\u00a0per l\u2019attuazione di opere di efficientamento.","breadcrumb":{"@id":"https:\/\/hw.mipu.eu\/fr\/prodotto\/corso-online-comprehensive-energy-management\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hw.mipu.eu\/fr\/prodotto\/corso-online-comprehensive-energy-management\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hw.mipu.eu\/fr\/prodotto\/corso-online-comprehensive-energy-management\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hw.mipu.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"CORSO ONLINE &#8211; COMPREHENSIVE ENERGY MANAGEMENT"}]},{"@type":"WebSite","@id":"https:\/\/hw.mipu.eu\/fr\/#website","url":"https:\/\/hw.mipu.eu\/fr\/","name":"Mipu Hardware","description":"Predictive Hub","publisher":{"@id":"https:\/\/hw.mipu.eu\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hw.mipu.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/hw.mipu.eu\/fr\/#organization","name":"Mipu Hardware","url":"https:\/\/hw.mipu.eu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/hw.mipu.eu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/hw.mipu.eu\/wp-content\/uploads\/sites\/5\/2020\/04\/cropped-Logotipo-MIPU.png","contentUrl":"https:\/\/hw.mipu.eu\/wp-content\/uploads\/sites\/5\/2020\/04\/cropped-Logotipo-MIPU.png","width":1523,"height":588,"caption":"Mipu Hardware"},"image":{"@id":"https:\/\/hw.mipu.eu\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hw.mipu.eu\/fr\/wp-json\/wp\/v2\/product\/14641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hw.mipu.eu\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/hw.mipu.eu\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/hw.mipu.eu\/fr\/wp-json\/wp\/v2\/comments?post=14641"}],"wp:attachment":[{"href":"https:\/\/hw.mipu.eu\/fr\/wp-json\/wp\/v2\/media?parent=14641"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/hw.mipu.eu\/fr\/wp-json\/wp\/v2\/product_cat?post=14641"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/hw.mipu.eu\/fr\/wp-json\/wp\/v2\/product_tag?post=14641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}